{"id":9,"date":"2024-12-23T23:32:47","date_gmt":"2024-12-24T02:32:47","guid":{"rendered":"http:\/\/taylor.localhost\/?page_id=9"},"modified":"2026-03-26T10:45:50","modified_gmt":"2026-03-26T13:45:50","slug":"nosotros","status":"publish","type":"page","link":"https:\/\/www.iantaylor.com\/es\/nosotros\/","title":{"rendered":"Nosotros"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-about.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nosotros -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iantaylor.com\/es\/nosotros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nosotros -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iantaylor.com\/es\/nosotros\/\" \/>\n<meta property=\"og:site_name\" content=\"Empresas Taylor\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T13:45:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nosotros -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iantaylor.com\/es\/nosotros\/","og_locale":"es_ES","og_type":"article","og_title":"Nosotros -","og_url":"https:\/\/www.iantaylor.com\/es\/nosotros\/","og_site_name":"Empresas Taylor","article_modified_time":"2026-03-26T13:45:50+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.iantaylor.com\/es\/nosotros\/","url":"https:\/\/www.iantaylor.com\/es\/nosotros\/","name":"Nosotros -","isPartOf":{"@id":"https:\/\/www.iantaylor.com\/es\/#website"},"datePublished":"2024-12-24T02:32:47+00:00","dateModified":"2026-03-26T13:45:50+00:00","breadcrumb":{"@id":"https:\/\/www.iantaylor.com\/es\/nosotros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iantaylor.com\/es\/nosotros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.iantaylor.com\/es\/nosotros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iantaylor.com\/es\/"},{"@type":"ListItem","position":2,"name":"Nosotros"}]},{"@type":"WebSite","@id":"https:\/\/www.iantaylor.com\/es\/#website","url":"https:\/\/www.iantaylor.com\/es\/","name":"Ian Taylor","description":"Con m\u00e1s de medio siglo conectando la log\u00edstica mar\u00edtima con excelencia y experiencia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iantaylor.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.iantaylor.com\/es\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iantaylor.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.iantaylor.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.iantaylor.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iantaylor.com\/es\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":19,"href":"https:\/\/www.iantaylor.com\/es\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":3686,"href":"https:\/\/www.iantaylor.com\/es\/wp-json\/wp\/v2\/pages\/9\/revisions\/3686"}],"wp:attachment":[{"href":"https:\/\/www.iantaylor.com\/es\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}